{"id":6091,"date":"2011-02-15T07:43:37","date_gmt":"2011-02-15T07:43:37","guid":{"rendered":"http:\/\/blogs.oulipo.net\/qc\/?p=6091"},"modified":"2011-03-10T07:50:13","modified_gmt":"2011-03-10T07:50:13","slug":"1958-16","status":"publish","type":"post","link":"https:\/\/blogs.oulipo.net\/qc\/2011\/02\/15\/1958-16\/","title":{"rendered":"Murailles? Non, mailles \u2014 1958 (16)"},"content":{"rendered":"<p>&#8211; <strong>Jean Tardieu<\/strong> in <em>Margeries<\/em><\/p>\n<p><span style=\"text-decoration: underline\">Sonnet au galop<br \/>\n<\/span><br \/>\nMurailles? Non, mailles<br \/>\nMai mugissement,<br \/>\nToi moi que travaille<br \/>\nLe commencement<\/p>\n<p>Mais mains et mes dents<br \/>\nmordent\u00a0 les t\u00e9n\u00e8bres,<br \/>\nle marteau du temps<br \/>\ncogne \u00e0 mes vert\u00e8bres<\/p>\n<p>Qui dit mieux? J&rsquo;\u00e9coute<br \/>\ngalop \u00e0 l&rsquo;envers<br \/>\nl&rsquo;oreille \u00e0 la route<\/p>\n<p>Sabots et crini\u00e8re<br \/>\nles yeux les \u00e9clairs<br \/>\nla terre la terre!<\/p>\n<p>Q35 &#8211; T21 &#8211; 5s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Jean Tardieu in Margeries Sonnet au galop Murailles? Non, mailles Mai mugissement, Toi moi que travaille Le commencement Mais mains et mes dents mordent\u00a0 les t\u00e9n\u00e8bres, le marteau du temps cogne \u00e0 mes vert\u00e8bres Qui dit mieux? J&rsquo;\u00e9coute galop \u00e0 l&rsquo;envers l&rsquo;oreille \u00e0 la route Sabots et crini\u00e8re les yeux les \u00e9clairs la terre &hellip; <a href=\"https:\/\/blogs.oulipo.net\/qc\/2011\/02\/15\/1958-16\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Murailles? Non, mailles \u2014 1958 (16)<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1357,1244,1172,1211],"tags":[],"class_list":["post-6091","post","type-post","status-publish","format-standard","hentry","category-malh","category-5s","category-q35-abab-baba","category-t22-cdc-ddd"],"_links":{"self":[{"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/posts\/6091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/comments?post=6091"}],"version-history":[{"count":6,"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/posts\/6091\/revisions"}],"predecessor-version":[{"id":10254,"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/posts\/6091\/revisions\/10254"}],"wp:attachment":[{"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/media?parent=6091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/categories?post=6091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.oulipo.net\/qc\/wp-json\/wp\/v2\/tags?post=6091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}